{"id":4062,"name":"Diede Hogeweg","url":"","description":"","link":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/","slug":"diede-hogeweg","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/bb27da60c1bb3b66d1d0de5f751b98523ec4b89177def44d17a102ace76cb800?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/bb27da60c1bb3b66d1d0de5f751b98523ec4b89177def44d17a102ace76cb800?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/bb27da60c1bb3b66d1d0de5f751b98523ec4b89177def44d17a102ace76cb800?s=96&d=mm&r=g"},"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diede Hogeweg, Author at Culemborg<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Diede Hogeweg, Author at Culemborg\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/\" \/>\n<meta property=\"og:site_name\" content=\"Culemborg\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/author\\\/diede-hogeweg\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/author\\\/diede-hogeweg\\\/\",\"name\":\"Diede Hogeweg, Author at Culemborg\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/author\\\/diede-hogeweg\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/author\\\/diede-hogeweg\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/author\\\/diede-hogeweg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Diede Hogeweg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/\",\"name\":\"Culemborg\",\"description\":\"HU School voor Journalistiek Regiosite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/#\\\/schema\\\/person\\\/1d754d27990cfedfc457cb5fd02325b6\",\"name\":\"Diede Hogeweg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/wp-content\\\/uploads\\\/sites\\\/1802\\\/2025\\\/09\\\/IMG_7112-96x96.jpg\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/wp-content\\\/uploads\\\/sites\\\/1802\\\/2025\\\/09\\\/IMG_7112-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/wp-content\\\/uploads\\\/sites\\\/1802\\\/2025\\\/09\\\/IMG_7112-96x96.jpg\",\"caption\":\"Diede Hogeweg\"},\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/culemborg\\\/author\\\/diede-hogeweg\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diede Hogeweg, Author at Culemborg","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"profile","og_title":"Diede Hogeweg, Author at Culemborg","og_url":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/","og_site_name":"Culemborg","og_image":[{"width":1920,"height":2560,"url":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/","url":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/","name":"Diede Hogeweg, Author at Culemborg","isPartOf":{"@id":"https:\/\/svjmedia.nl\/culemborg\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/culemborg\/"},{"@type":"ListItem","position":2,"name":"Archives for Diede Hogeweg"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/culemborg\/#website","url":"https:\/\/svjmedia.nl\/culemborg\/","name":"Culemborg","description":"HU School voor Journalistiek Regiosite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/culemborg\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/svjmedia.nl\/culemborg\/#\/schema\/person\/1d754d27990cfedfc457cb5fd02325b6","name":"Diede Hogeweg","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-96x96.jpg","url":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-96x96.jpg","contentUrl":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-96x96.jpg","caption":"Diede Hogeweg"},"mainEntityOfPage":{"@id":"https:\/\/svjmedia.nl\/culemborg\/author\/diede-hogeweg\/"}}]}},"mpp_avatar":{"24":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-24x24.jpg","48":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-48x48.jpg","96":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-96x96.jpg","150":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-150x150.jpg","300":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-300x300.jpg","full":"https:\/\/svjmedia.nl\/culemborg\/wp-content\/uploads\/sites\/1802\/2025\/09\/IMG_7112-scaled.jpg"},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/culemborg\/wp-json\/wp\/v2\/users\/4062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/culemborg\/wp-json\/wp\/v2\/users"}]}}