{"id":173,"count":1,"description":"","link":"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/","name":"alcohol","slug":"alcohol","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>alcohol Archives - Datablog<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"alcohol Archives - Datablog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/\" \/>\n<meta property=\"og:site_name\" content=\"Datablog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/tag\\\/alcohol\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/tag\\\/alcohol\\\/\",\"name\":\"alcohol Archives - Datablog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/tag\\\/alcohol\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/tag\\\/alcohol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"alcohol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/\",\"name\":\"Datablog\",\"description\":\"HU School voor Journalistiek - Datablog van de minor Datavisualisatie &amp; Infographics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/datablog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"alcohol Archives - Datablog","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"alcohol Archives - Datablog","og_url":"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/","og_site_name":"Datablog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/","url":"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/","name":"alcohol Archives - Datablog","isPartOf":{"@id":"https:\/\/svjmedia.nl\/datablog\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/datablog\/tag\/alcohol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/datablog\/"},{"@type":"ListItem","position":2,"name":"alcohol"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/datablog\/#website","url":"https:\/\/svjmedia.nl\/datablog\/","name":"Datablog","description":"HU School voor Journalistiek - Datablog van de minor Datavisualisatie &amp; Infographics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/datablog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/datablog\/wp-json\/wp\/v2\/tags\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/datablog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/svjmedia.nl\/datablog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/svjmedia.nl\/datablog\/wp-json\/wp\/v2\/posts?tags=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}