{"id":461,"count":1,"description":"","link":"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/","name":"Restoration","slug":"restoration","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restoration Archives - International Journalism<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restoration Archives - International Journalism\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/\" \/>\n<meta property=\"og:site_name\" content=\"International Journalism\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/tag\\\/restoration\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/tag\\\/restoration\\\/\",\"name\":\"Restoration Archives - International Journalism\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/tag\\\/restoration\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/tag\\\/restoration\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restoration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/\",\"name\":\"International Journalism\",\"description\":\"HU School voor Journalistiek Nieuwssite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/internationaljournalism\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restoration Archives - International Journalism","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Restoration Archives - International Journalism","og_url":"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/","og_site_name":"International Journalism","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/","url":"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/","name":"Restoration Archives - International Journalism","isPartOf":{"@id":"https:\/\/svjmedia.nl\/internationaljournalism\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/internationaljournalism\/tag\/restoration\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/internationaljournalism\/"},{"@type":"ListItem","position":2,"name":"Restoration"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/internationaljournalism\/#website","url":"https:\/\/svjmedia.nl\/internationaljournalism\/","name":"International Journalism","description":"HU School voor Journalistiek Nieuwssite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/internationaljournalism\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/internationaljournalism\/wp-json\/wp\/v2\/tags\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/internationaljournalism\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/svjmedia.nl\/internationaljournalism\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/svjmedia.nl\/internationaljournalism\/wp-json\/wp\/v2\/posts?tags=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}