{"id":1912,"name":"Ottelien Devilee","url":"","description":"Hii, mijn naam is Ottelien Devilee en ik ben 18 jaar oud. Ik zit in mijn eerste jaar van de opleiding Journalistiek en heb het heel erg naar mijn zin! Schrijven doe ik vanuit mijn hart en het liefste over verschillende dingen die ik mee maak. Verder luister ik graag naar podcasts waar ik hard om kan lachen of waar ik wat van kan leren.","link":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/","slug":"ottelien-devilee","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g"},"meta":{"getwid_ai_accept_terms":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ottelien Devilee, Author at SVJ Specialisaties<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Ottelien Devilee, Author at SVJ Specialisaties\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/\" \/>\n<meta property=\"og:site_name\" content=\"SVJ Specialisaties\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/e5de950286e041b8d985b73c9b2deb7e?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/ottelien-devilee\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/ottelien-devilee\\\/\",\"name\":\"Ottelien Devilee, Author at SVJ Specialisaties\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/ottelien-devilee\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/ottelien-devilee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/ottelien-devilee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Ottelien Devilee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/\",\"name\":\"SVJ Specialisaties\",\"description\":\"HU School voor Journalistiek Regiosite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/#\\\/schema\\\/person\\\/e1581a778b9a88d29c68c6733d01e069\",\"name\":\"Ottelien Devilee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g\",\"caption\":\"Ottelien Devilee\"},\"description\":\"Hii, mijn naam is Ottelien Devilee en ik ben 18 jaar oud. Ik zit in mijn eerste jaar van de opleiding Journalistiek en heb het heel erg naar mijn zin! Schrijven doe ik vanuit mijn hart en het liefste over verschillende dingen die ik mee maak. Verder luister ik graag naar podcasts waar ik hard om kan lachen of waar ik wat van kan leren.\",\"sameAs\":[\"otteliendevilee\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/ottelien-devilee\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ottelien Devilee, Author at SVJ Specialisaties","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"profile","og_title":"Ottelien Devilee, Author at SVJ Specialisaties","og_url":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/","og_site_name":"SVJ Specialisaties","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/e5de950286e041b8d985b73c9b2deb7e?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/","url":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/","name":"Ottelien Devilee, Author at SVJ Specialisaties","isPartOf":{"@id":"https:\/\/svjmedia.nl\/specialisaties\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/specialisaties\/"},{"@type":"ListItem","position":2,"name":"Archives for Ottelien Devilee"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/specialisaties\/#website","url":"https:\/\/svjmedia.nl\/specialisaties\/","name":"SVJ Specialisaties","description":"HU School voor Journalistiek Regiosite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/specialisaties\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/svjmedia.nl\/specialisaties\/#\/schema\/person\/e1581a778b9a88d29c68c6733d01e069","name":"Ottelien Devilee","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eec633f48b6878226e25cbf2d37174c6cd9e76533efba2f75d236293e1556e0a?s=96&d=mm&r=g","caption":"Ottelien Devilee"},"description":"Hii, mijn naam is Ottelien Devilee en ik ben 18 jaar oud. Ik zit in mijn eerste jaar van de opleiding Journalistiek en heb het heel erg naar mijn zin! Schrijven doe ik vanuit mijn hart en het liefste over verschillende dingen die ik mee maak. Verder luister ik graag naar podcasts waar ik hard om kan lachen of waar ik wat van kan leren.","sameAs":["otteliendevilee"],"mainEntityOfPage":{"@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/ottelien-devilee\/"}}]}},"mpp_avatar":{"errors":{"mpp_no_profile_picture":["Profielfoto niet gevonden."]},"error_data":{"mpp_no_profile_picture":{"status":404}}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/specialisaties\/wp-json\/wp\/v2\/users\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/specialisaties\/wp-json\/wp\/v2\/users"}]}}