{"id":2234,"name":"Job Ploeger","url":"","description":"Ik ben 21 jaar, kom uit Alphen a\/d Rijn. Twee jaar terug ben ik begonnen met reizen waarbij ik er achter ben gekomen dat ik het heel tof vind om verhalen van mensen aan te horen. Het blijkt dat er veel mensen zijn met een verhaal (dat waard is om aan te horen), en op het moment wil ik het dan ook mijn missie maken om die verhalen weer door te vertellen als journalist.","link":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/","slug":"job-ploeger","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g"},"meta":{"getwid_ai_accept_terms":true},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Job Ploeger, Author at SVJ Specialisaties<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Job Ploeger, Author at SVJ Specialisaties\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/\" \/>\n<meta property=\"og:site_name\" content=\"SVJ Specialisaties\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/job-ploeger\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/job-ploeger\\\/\",\"name\":\"Job Ploeger, Author at SVJ Specialisaties\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/job-ploeger\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/job-ploeger\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/job-ploeger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Job Ploeger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/\",\"name\":\"SVJ Specialisaties\",\"description\":\"HU School voor Journalistiek Regiosite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/#\\\/schema\\\/person\\\/fb572d22157524bef93129fbeeb74efc\",\"name\":\"Job Ploeger\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g\",\"caption\":\"Job Ploeger\"},\"description\":\"Ik ben 21 jaar, kom uit Alphen a\\\/d Rijn. Twee jaar terug ben ik begonnen met reizen waarbij ik er achter ben gekomen dat ik het heel tof vind om verhalen van mensen aan te horen. Het blijkt dat er veel mensen zijn met een verhaal (dat waard is om aan te horen), en op het moment wil ik het dan ook mijn missie maken om die verhalen weer door te vertellen als journalist.\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/specialisaties\\\/author\\\/job-ploeger\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Job Ploeger, Author at SVJ Specialisaties","robots":{"index":"noindex","follow":"follow"},"og_locale":"nl_NL","og_type":"profile","og_title":"Job Ploeger, Author at SVJ Specialisaties","og_url":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/","og_site_name":"SVJ Specialisaties","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=500&d=mm&r=g","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/","url":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/","name":"Job Ploeger, Author at SVJ Specialisaties","isPartOf":{"@id":"https:\/\/svjmedia.nl\/specialisaties\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/specialisaties\/"},{"@type":"ListItem","position":2,"name":"Archives for Job Ploeger"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/specialisaties\/#website","url":"https:\/\/svjmedia.nl\/specialisaties\/","name":"SVJ Specialisaties","description":"HU School voor Journalistiek Regiosite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/specialisaties\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/svjmedia.nl\/specialisaties\/#\/schema\/person\/fb572d22157524bef93129fbeeb74efc","name":"Job Ploeger","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0386b37891202510d9932f503d0e5a74d60ebbd3cf4e5377ae8262429239572d?s=96&d=mm&r=g","caption":"Job Ploeger"},"description":"Ik ben 21 jaar, kom uit Alphen a\/d Rijn. Twee jaar terug ben ik begonnen met reizen waarbij ik er achter ben gekomen dat ik het heel tof vind om verhalen van mensen aan te horen. Het blijkt dat er veel mensen zijn met een verhaal (dat waard is om aan te horen), en op het moment wil ik het dan ook mijn missie maken om die verhalen weer door te vertellen als journalist.","mainEntityOfPage":{"@id":"https:\/\/svjmedia.nl\/specialisaties\/author\/job-ploeger\/"}}]}},"mpp_avatar":{"errors":{"mpp_no_profile_picture":["Profielfoto niet gevonden."]},"error_data":{"mpp_no_profile_picture":{"status":404}}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/specialisaties\/wp-json\/wp\/v2\/users\/2234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/specialisaties\/wp-json\/wp\/v2\/users"}]}}