{"id":34,"count":1,"description":"","link":"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/","name":"witwassen horeca","slug":"witwassen-horeca","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>witwassen horeca Archives - Tijmen Beijes<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"witwassen horeca Archives - Tijmen Beijes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/\" \/>\n<meta property=\"og:site_name\" content=\"Tijmen Beijes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/tag\\\/witwassen-horeca\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/tag\\\/witwassen-horeca\\\/\",\"name\":\"witwassen horeca Archives - Tijmen Beijes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/tag\\\/witwassen-horeca\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/tag\\\/witwassen-horeca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"witwassen horeca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/\",\"name\":\"Tijmen Beijes\",\"description\":\"Portfolio\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/tijmenbeijes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"witwassen horeca Archives - Tijmen Beijes","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"witwassen horeca Archives - Tijmen Beijes","og_url":"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/","og_site_name":"Tijmen Beijes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/","url":"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/","name":"witwassen horeca Archives - Tijmen Beijes","isPartOf":{"@id":"https:\/\/svjmedia.nl\/tijmenbeijes\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/tijmenbeijes\/tag\/witwassen-horeca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/tijmenbeijes\/"},{"@type":"ListItem","position":2,"name":"witwassen horeca"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/tijmenbeijes\/#website","url":"https:\/\/svjmedia.nl\/tijmenbeijes\/","name":"Tijmen Beijes","description":"Portfolio","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/tijmenbeijes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/tijmenbeijes\/wp-json\/wp\/v2\/tags\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/tijmenbeijes\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/svjmedia.nl\/tijmenbeijes\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/svjmedia.nl\/tijmenbeijes\/wp-json\/wp\/v2\/posts?tags=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}