{"id":1502,"date":"2025-12-01T07:51:25","date_gmt":"2025-12-01T06:51:25","guid":{"rendered":"https:\/\/svjmedia.nl\/woerden\/?p=1502"},"modified":"2025-12-19T12:26:26","modified_gmt":"2025-12-19T11:26:26","slug":"computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting","status":"publish","type":"post","link":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/","title":{"rendered":"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting"},"content":{"rendered":"<p>WOERDEN- Uit een recent onderzoek onder leden van SeniorWeb blijkt 15% van de senioren wel eens online opgelicht te zijn. Dit is een een forse stijging tegenover de 11% in 2023.<\/p>\n<p>Luister onderstaand naar een interview met Bas Heijkamp. Hij werkt bij Bibliotheek Woerden, waar ze computerhulp voor senioren aanbieden. Ook hij merkt de impact van online oplichting onder de senioren in Woerden.<\/p>\n<p>&nbsp;<\/p>\n<p><span data-olk-copy-source=\"MessageBody\"> <div class=\"humamaudio\" style=\"position:relative;overflow:hidden;width:600px;height:40px;margin:20px 0px;\"><iframe loading=\"lazy\" width=\"600\" height=\"40\" src=\"https:\/\/stream.hu.nl\/players\/yYlbdsL7-gUDjC9bv.html\"><\/iframe><\/div><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WOERDEN- Uit een recent onderzoek onder leden van SeniorWeb blijkt 15% van de senioren wel eens online opgelicht te zijn. Dit is een een forse stijging tegenover de 11% in 2023. Luister onderstaand naar een interview met Bas Heijkamp. Hij werkt bij Bibliotheek Woerden, waar ze computerhulp voor senioren aanbieden. Ook hij merkt de impact [&hellip;]<\/p>\n","protected":false},"author":3961,"featured_media":1690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultuur-vrije-tijd","et-has-post-format-content","et_post_format-et-post-format-standard"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting - Woerden<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting - Woerden\" \/>\n<meta property=\"og:description\" content=\"WOERDEN- Uit een recent onderzoek onder leden van SeniorWeb blijkt 15% van de senioren wel eens online opgelicht te zijn. Dit is een een forse stijging tegenover de 11% in 2023. Luister onderstaand naar een interview met Bas Heijkamp. Hij werkt bij Bibliotheek Woerden, waar ze computerhulp voor senioren aanbieden. Ook hij merkt de impact [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/\" \/>\n<meta property=\"og:site_name\" content=\"Woerden\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T06:51:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T11:26:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/12\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guusje Stijns\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guusje Stijns\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/\"},\"author\":{\"name\":\"Guusje Stijns\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#\\\/schema\\\/person\\\/c1d0afb2a5fc03d74005d93a710c8b39\"},\"headline\":\"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting\",\"datePublished\":\"2025-12-01T06:51:25+00:00\",\"dateModified\":\"2025-12-19T11:26:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/\"},\"wordCount\":76,\"image\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg\",\"articleSection\":[\"Cultuur &amp; vrije tijd\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/\",\"name\":\"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting - Woerden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg\",\"datePublished\":\"2025-12-01T06:51:25+00:00\",\"dateModified\":\"2025-12-19T11:26:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#\\\/schema\\\/person\\\/c1d0afb2a5fc03d74005d93a710c8b39\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg\",\"contentUrl\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/1502\\\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/\",\"name\":\"Woerden\",\"description\":\"HU School voor Journalistiek Regiosite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#\\\/schema\\\/person\\\/c1d0afb2a5fc03d74005d93a710c8b39\",\"name\":\"Guusje Stijns\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/09\\\/Profielfoto-SVJ-Media-96x96.jpg\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/09\\\/Profielfoto-SVJ-Media-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/wp-content\\\/uploads\\\/sites\\\/1798\\\/2025\\\/09\\\/Profielfoto-SVJ-Media-96x96.jpg\",\"caption\":\"Guusje Stijns\"},\"description\":\"Hoi! Mijn naam is Guusje Stijns, 18 jaar en momenteel studeer ik aan de Hogeschool Utrecht Journalistiek. Hiervoor heb ik 1e jaar acteursopleiding gedaan in Heerlen. In 2024 heb ik mijn Havo diploma gehaald bij het Bernard Lievegoed College. Al van jongs af aan ben ik in contact met het nieuws. Zo hebben mijn ouders mij aangeleerd om elke dag het journaal te kijken. Hier is mijn interesse in journalistiek begonnen. Vooral correspondentie vind ik heel interessant. Dit komt door mijn passie voor reizen en nieuwe culturen leren kennen. Mijn doel binnen de journalistiek is dan ook correspondent Azi\u00eb te zijn voor een nieuwszender. Maar eerst ga ik nieuws maken in Amersfoort, wat voor mij ook al wat correspondentie werk is aangezien ik uit het zuidelijkste puntje van Limburg kom. Tips en vragen zie ik natuurlijk altijd graag binnenkomen. Dat kan telefonisch of via de mail! Tel.; 06 25334534 E-mail: Guusje.stijns@student.hu.nl\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/author\\\/guusje-stijns\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting - Woerden","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting - Woerden","og_description":"WOERDEN- Uit een recent onderzoek onder leden van SeniorWeb blijkt 15% van de senioren wel eens online opgelicht te zijn. Dit is een een forse stijging tegenover de 11% in 2023. Luister onderstaand naar een interview met Bas Heijkamp. Hij werkt bij Bibliotheek Woerden, waar ze computerhulp voor senioren aanbieden. Ook hij merkt de impact [&hellip;]","og_url":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/","og_site_name":"Woerden","article_published_time":"2025-12-01T06:51:25+00:00","article_modified_time":"2025-12-19T11:26:26+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/12\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg","type":"image\/jpeg"}],"author":"Guusje Stijns","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Guusje Stijns"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#article","isPartOf":{"@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/"},"author":{"name":"Guusje Stijns","@id":"https:\/\/svjmedia.nl\/woerden\/#\/schema\/person\/c1d0afb2a5fc03d74005d93a710c8b39"},"headline":"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting","datePublished":"2025-12-01T06:51:25+00:00","dateModified":"2025-12-19T11:26:26+00:00","mainEntityOfPage":{"@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/"},"wordCount":76,"image":{"@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#primaryimage"},"thumbnailUrl":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/12\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg","articleSection":["Cultuur &amp; vrije tijd"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/","url":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/","name":"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting - Woerden","isPartOf":{"@id":"https:\/\/svjmedia.nl\/woerden\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#primaryimage"},"image":{"@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#primaryimage"},"thumbnailUrl":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/12\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg","datePublished":"2025-12-01T06:51:25+00:00","dateModified":"2025-12-19T11:26:26+00:00","author":{"@id":"https:\/\/svjmedia.nl\/woerden\/#\/schema\/person\/c1d0afb2a5fc03d74005d93a710c8b39"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#primaryimage","url":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/12\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg","contentUrl":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/12\/WhatsApp-Image-2025-12-19-at-12.23.51.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/woerden\/1502\/computerhulp-voor-senioren-bij-bibliotheek-woerden-strijdt-tegen-online-oplichting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/woerden\/"},{"@type":"ListItem","position":2,"name":"Computerhulp voor senioren bij Bibliotheek Woerden strijdt tegen online oplichting"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/woerden\/#website","url":"https:\/\/svjmedia.nl\/woerden\/","name":"Woerden","description":"HU School voor Journalistiek Regiosite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/woerden\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/svjmedia.nl\/woerden\/#\/schema\/person\/c1d0afb2a5fc03d74005d93a710c8b39","name":"Guusje Stijns","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/09\/Profielfoto-SVJ-Media-96x96.jpg","url":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/09\/Profielfoto-SVJ-Media-96x96.jpg","contentUrl":"https:\/\/svjmedia.nl\/woerden\/wp-content\/uploads\/sites\/1798\/2025\/09\/Profielfoto-SVJ-Media-96x96.jpg","caption":"Guusje Stijns"},"description":"Hoi! Mijn naam is Guusje Stijns, 18 jaar en momenteel studeer ik aan de Hogeschool Utrecht Journalistiek. Hiervoor heb ik 1e jaar acteursopleiding gedaan in Heerlen. In 2024 heb ik mijn Havo diploma gehaald bij het Bernard Lievegoed College. Al van jongs af aan ben ik in contact met het nieuws. Zo hebben mijn ouders mij aangeleerd om elke dag het journaal te kijken. Hier is mijn interesse in journalistiek begonnen. Vooral correspondentie vind ik heel interessant. Dit komt door mijn passie voor reizen en nieuwe culturen leren kennen. Mijn doel binnen de journalistiek is dan ook correspondent Azi\u00eb te zijn voor een nieuwszender. Maar eerst ga ik nieuws maken in Amersfoort, wat voor mij ook al wat correspondentie werk is aangezien ik uit het zuidelijkste puntje van Limburg kom. Tips en vragen zie ik natuurlijk altijd graag binnenkomen. Dat kan telefonisch of via de mail! Tel.; 06 25334534 E-mail: Guusje.stijns@student.hu.nl","url":"https:\/\/svjmedia.nl\/woerden\/author\/guusje-stijns\/"}]}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/posts\/1502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/users\/3961"}],"replies":[{"embeddable":true,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/comments?post=1502"}],"version-history":[{"count":4,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/posts\/1502\/revisions"}],"predecessor-version":[{"id":1647,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/posts\/1502\/revisions\/1647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/media\/1690"}],"wp:attachment":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/media?parent=1502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/categories?post=1502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/tags?post=1502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}