{"id":77,"count":1,"description":"","link":"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/","name":"The Wieners","slug":"the-wieners","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Wieners Archives - Woerden<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Wieners Archives - Woerden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/\" \/>\n<meta property=\"og:site_name\" content=\"Woerden\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/tag\\\/the-wieners\\\/\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/tag\\\/the-wieners\\\/\",\"name\":\"The Wieners Archives - Woerden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/tag\\\/the-wieners\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/tag\\\/the-wieners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Wieners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/#website\",\"url\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/\",\"name\":\"Woerden\",\"description\":\"HU School voor Journalistiek Regiosite\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svjmedia.nl\\\/woerden\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Wieners Archives - Woerden","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"nl_NL","og_type":"article","og_title":"The Wieners Archives - Woerden","og_url":"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/","og_site_name":"Woerden","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/","url":"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/","name":"The Wieners Archives - Woerden","isPartOf":{"@id":"https:\/\/svjmedia.nl\/woerden\/#website"},"breadcrumb":{"@id":"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/svjmedia.nl\/woerden\/tag\/the-wieners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/svjmedia.nl\/woerden\/"},{"@type":"ListItem","position":2,"name":"The Wieners"}]},{"@type":"WebSite","@id":"https:\/\/svjmedia.nl\/woerden\/#website","url":"https:\/\/svjmedia.nl\/woerden\/","name":"Woerden","description":"HU School voor Journalistiek Regiosite","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svjmedia.nl\/woerden\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/tags\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/svjmedia.nl\/woerden\/wp-json\/wp\/v2\/posts?tags=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}